{"id":502,"date":"2020-04-16T15:15:26","date_gmt":"2020-04-16T18:15:26","guid":{"rendered":"http:\/\/www.aureacarolina.com.br\/camara\/?p=502"},"modified":"2020-06-16T20:18:46","modified_gmt":"2020-06-16T23:18:46","slug":"na-esfera-federal-pedimos-ao-ministerio-publico-do-trabalho-investigue-a-continuidade-das-atividades-mineradoras-durante-a-crise","status":"publish","type":"post","link":"https:\/\/www.aureacarolina.com.br\/camara\/2020\/04\/16\/na-esfera-federal-pedimos-ao-ministerio-publico-do-trabalho-investigue-a-continuidade-das-atividades-mineradoras-durante-a-crise\/","title":{"rendered":"Na esfera federal pedimos ao Minist\u00e9rio P\u00fablico do trabalho investigue a continuidade das atividades mineradoras durante a crise"},"content":{"rendered":"<p>Junto do colega de bancada Edmilson Rodrigues (PSOL\/PA), nosso mandato acionou o Minist\u00e9rio P\u00fablico do Trabalho (MPT) <strong>pedindo a revoga\u00e7\u00e3o da Portaria 135\/2020<\/strong>, do Minist\u00e9rio de Minas e Energia (MMA), q<em>ue permite a continuidade do funcionamento de setores da minera\u00e7\u00e3o durante a pandemia do coronav\u00edrus.<\/em><\/p>\n<p>A den\u00fancia vem em meio \u00e0 not\u00edcia da morte, em uma mineradora do Par\u00e1, de um trabalhador de 42 anos que n\u00e3o possu\u00eda comorbidades ou hist\u00f3rico de viagens. <strong>O funcionamento dessas atividades em plena crise sanit\u00e1ria apresenta enormes riscos de contamina\u00e7\u00e3o para os milhares de trabalhadores\/as do ramo, suas fam\u00edlias e as comunidades onde vivem e trabalham<\/strong>. A den\u00fancia foi encaminhada em nome da bancada de deputados do PSOL na C\u00e2mara.<\/p>\n<p>Uma evidente concess\u00e3o ao lobby do setor, <strong>a portaria 135 do MMA contraria um decreto anterior do pr\u00f3prio governo federal, que estabelece os servi\u00e7os p\u00fablicos e atividades essenciais para atender a popula\u00e7\u00e3o durante a pandemia<\/strong>. A minera\u00e7\u00e3o N\u00c3O consta nessa lista, portanto n\u00e3o deveria seguir durante a crise.<\/p>\n<p>Infelizmente, as mineradoras t\u00eam desenvolvido normalmente as suas atividades principais e secund\u00e1rias. V\u00e1rios relatos, v\u00eddeos e fotos enviados aos nossos mandatos e \u00e0 imprensa mostram trabalhadores circulando em \u00f4nibus, refeit\u00f3rios e cidades vizinhas \u00e0s zonas mineiras.<\/p>\n<p>Um dos casos emblem\u00e1ticos \u00e9 o da Vale, respons\u00e1vel por um dos maiores crimes socioambientais da hist\u00f3ria, que deixou 272 mortos em Brumadinho e danos irrepar\u00e1veis em toda a bacia do Paraopeba. <strong>A mineradora j\u00e1 diminuiu ou paralisou suas opera\u00e7\u00f5es no Canad\u00e1, Mal\u00e1sia e em Mo\u00e7ambique, entre outros pa\u00edses, mas, de maneira inexplic\u00e1vel, segue funcionando no Brasil<\/strong>.<\/p>\n<p>Al\u00e9m de solicitar a investiga\u00e7\u00e3o das ilegalidades, solicitamos que o MPT atue no sentido de garantir a prote\u00e7\u00e3o dos trabalhadores da minera\u00e7\u00e3o e a divulga\u00e7\u00e3o de boletins informativos por parte das mineradoras, informando os casos suspeitos e afastados por COVID-19 e tamb\u00e9m os locais onde se deu a contamina\u00e7\u00e3o, al\u00e9m da garantia de transporte seguro aos trabalhadores.<\/p>\n<p>Tamb\u00e9m pedimos que o MPT recomende \u00e0 C\u00e2mara dos Deputados a urg\u00eancia na vota\u00e7\u00e3o do Projeto de Decreto Legislativo que nossa bancada do PSOL apresentou \u00e0 Casa no in\u00edcio de abril, pedindo a revoga\u00e7\u00e3o da portaria do MMA.<\/p>\n<p><strong>N\u00e3o vamos tolerar que a minera\u00e7\u00e3o predat\u00f3ria siga avan\u00e7ando sobre nossa sa\u00fade e nossas vidas. <\/strong>Precisamos garantir o cuidado e a prote\u00e7\u00e3o social a esses trabalhadores!<\/p>\n<p class=\"has-text-color has-background has-very-dark-gray-color has-luminous-vivid-amber-background-color\" style=\"text-align: center;\">&gt;&gt; para receber not\u00edcias do nosso mandato pelo zap:\u00a0<a href=\"http:\/\/bit.ly\/ZapDaAurea\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/bit.ly\/<strong>ZapDaAurea<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Junto do colega de bancada Edmilson Rodrigues (PSOL\/PA), nosso mandato acionou o Minist\u00e9rio P\u00fablico do Trabalho (MPT) pedindo a revoga\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":503,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Na esfera federal pedimos ao Minist\u00e9rio P\u00fablico do trabalho investigue a continuidade das atividades mineradoras durante a crise - \u00c1urea Carolina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aureacarolina.com.br\/camara\/2020\/04\/16\/na-esfera-federal-pedimos-ao-ministerio-publico-do-trabalho-investigue-a-continuidade-das-atividades-mineradoras-durante-a-crise\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Na esfera federal pedimos ao Minist\u00e9rio P\u00fablico do trabalho investigue a continuidade das atividades mineradoras durante a crise - \u00c1urea Carolina\" \/>\n<meta property=\"og:description\" content=\"Junto do colega de bancada Edmilson Rodrigues (PSOL\/PA), nosso mandato acionou o Minist\u00e9rio P\u00fablico do Trabalho (MPT) pedindo a revoga\u00e7\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aureacarolina.com.br\/camara\/2020\/04\/16\/na-esfera-federal-pedimos-ao-ministerio-publico-do-trabalho-investigue-a-continuidade-das-atividades-mineradoras-durante-a-crise\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c1urea Carolina\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-16T18:15:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-16T23:18:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aureacarolina.com.br\/camara\/wp-content\/uploads\/2020\/06\/mineracao.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.aureacarolina.com.br\/camara\/#website\",\"url\":\"https:\/\/www.aureacarolina.com.br\/camara\/\",\"name\":\"\\u00c1urea Carolina\",\"description\":\"deputada federal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.aureacarolina.com.br\/camara\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.aureacarolina.com.br\/camara\/2020\/04\/16\/na-esfera-federal-pedimos-ao-ministerio-publico-do-trabalho-investigue-a-continuidade-das-atividades-mineradoras-durante-a-crise\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/www.aureacarolina.com.br\/camara\/wp-content\/uploads\/2020\/06\/mineracao.png\",\"contentUrl\":\"https:\/\/www.aureacarolina.com.br\/camara\/wp-content\/uploads\/2020\/06\/mineracao.png\",\"width\":1000,\"height\":1000},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.aureacarolina.com.br\/camara\/2020\/04\/16\/na-esfera-federal-pedimos-ao-ministerio-publico-do-trabalho-investigue-a-continuidade-das-atividades-mineradoras-durante-a-crise\/#webpage\",\"url\":\"https:\/\/www.aureacarolina.com.br\/camara\/2020\/04\/16\/na-esfera-federal-pedimos-ao-ministerio-publico-do-trabalho-investigue-a-continuidade-das-atividades-mineradoras-durante-a-crise\/\",\"name\":\"Na esfera federal pedimos ao Minist\\u00e9rio P\\u00fablico do trabalho investigue a continuidade das atividades mineradoras durante a crise - \\u00c1urea Carolina\",\"isPartOf\":{\"@id\":\"https:\/\/www.aureacarolina.com.br\/camara\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.aureacarolina.com.br\/camara\/2020\/04\/16\/na-esfera-federal-pedimos-ao-ministerio-publico-do-trabalho-investigue-a-continuidade-das-atividades-mineradoras-durante-a-crise\/#primaryimage\"},\"datePublished\":\"2020-04-16T18:15:26+00:00\",\"dateModified\":\"2020-06-16T23:18:46+00:00\",\"author\":{\"@id\":\"https:\/\/www.aureacarolina.com.br\/camara\/#\/schema\/person\/ea5a01c25f36c70fae3fe96859684ab1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.aureacarolina.com.br\/camara\/2020\/04\/16\/na-esfera-federal-pedimos-ao-ministerio-publico-do-trabalho-investigue-a-continuidade-das-atividades-mineradoras-durante-a-crise\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.aureacarolina.com.br\/camara\/2020\/04\/16\/na-esfera-federal-pedimos-ao-ministerio-publico-do-trabalho-investigue-a-continuidade-das-atividades-mineradoras-durante-a-crise\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.aureacarolina.com.br\/camara\/2020\/04\/16\/na-esfera-federal-pedimos-ao-ministerio-publico-do-trabalho-investigue-a-continuidade-das-atividades-mineradoras-durante-a-crise\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.aureacarolina.com.br\/camara\/\",\"url\":\"https:\/\/www.aureacarolina.com.br\/camara\/\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/www.aureacarolina.com.br\/camara\/2020\/04\/16\/na-esfera-federal-pedimos-ao-ministerio-publico-do-trabalho-investigue-a-continuidade-das-atividades-mineradoras-durante-a-crise\/#webpage\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.aureacarolina.com.br\/camara\/#\/schema\/person\/ea5a01c25f36c70fae3fe96859684ab1\",\"name\":\"AdmAurea\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.aureacarolina.com.br\/camara\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/21a05777d1847c3fb829a6c9f224ea0d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/21a05777d1847c3fb829a6c9f224ea0d?s=96&d=mm&r=g\",\"caption\":\"AdmAurea\"},\"url\":\"https:\/\/www.aureacarolina.com.br\/camara\/author\/admaurea\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.aureacarolina.com.br\/camara\/wp-json\/wp\/v2\/posts\/502"}],"collection":[{"href":"https:\/\/www.aureacarolina.com.br\/camara\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aureacarolina.com.br\/camara\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aureacarolina.com.br\/camara\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aureacarolina.com.br\/camara\/wp-json\/wp\/v2\/comments?post=502"}],"version-history":[{"count":1,"href":"https:\/\/www.aureacarolina.com.br\/camara\/wp-json\/wp\/v2\/posts\/502\/revisions"}],"predecessor-version":[{"id":504,"href":"https:\/\/www.aureacarolina.com.br\/camara\/wp-json\/wp\/v2\/posts\/502\/revisions\/504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aureacarolina.com.br\/camara\/wp-json\/wp\/v2\/media\/503"}],"wp:attachment":[{"href":"https:\/\/www.aureacarolina.com.br\/camara\/wp-json\/wp\/v2\/media?parent=502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aureacarolina.com.br\/camara\/wp-json\/wp\/v2\/categories?post=502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aureacarolina.com.br\/camara\/wp-json\/wp\/v2\/tags?post=502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}